{"id":1330,"date":"2020-03-02T17:34:27","date_gmt":"2020-03-02T17:34:27","guid":{"rendered":"http:\/\/mikielantonvassallicollege.gov.mt\/?p=1330"},"modified":"2020-07-06T17:35:30","modified_gmt":"2020-07-06T16:35:30","slug":"xerrdu-l-arti-mhux-il-mikrobi","status":"publish","type":"post","link":"https:\/\/mikielantonvassallicollege.gov.mt\/mt\/xerrdu-l-arti-mhux-il-mikrobi\/","title":{"rendered":"Xerrdu l-ARTI mhux il-mikrobi"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" width=\"800\" height=\"600\" data-src=\"http:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/MAVC-Hall-School-of-Music.jpg\" alt=\"\" class=\"wp-image-982 lazyload\" data-srcset=\"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/MAVC-Hall-School-of-Music.jpg 800w, https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/MAVC-Hall-School-of-Music-400x300.jpg 400w, https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/MAVC-Hall-School-of-Music-768x576.jpg 768w, https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/MAVC-Hall-School-of-Music-174x132.jpg 174w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/600;\" \/><figcaption>Online Post #SpreadArtNotGerms<\/figcaption><\/figure><\/div>\n\n\n\n<p>Wara li \u0121ew installati l-hand sanitisers fil-kuruturi kollha tal-iskola, l-Iskola tal-Arti Vi\u017cwali u Performattiva, qed tnedi   &nbsp;\u201c<strong>SPREAD ART NOT GERMS<\/strong>\u201d&nbsp;g\u0127aliex l-Arti, il-Mu\u017cika, id-Drama u d-Dance huma parti mill-espressjoni tan-natura umana li tibqa\u2019 g\u0127addejja ji\u0121ri x\u2019ji\u0121ri! <\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<ul class=\"wp-block-gallery aligncenter columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"800\" height=\"600\" data-src=\"http:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/Main-Hall-Mikiel-Anton-Vassalli-College-Malta-School-of-Music.jpg\" alt=\"\" data-id=\"977\" data-link=\"http:\/\/vpa.mikielantonvassallicollege.gov.mt\/?attachment_id=977\" class=\"wp-image-977 lazyload\" data-srcset=\"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/Main-Hall-Mikiel-Anton-Vassalli-College-Malta-School-of-Music.jpg 800w, https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/Main-Hall-Mikiel-Anton-Vassalli-College-Malta-School-of-Music-400x300.jpg 400w, https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/Main-Hall-Mikiel-Anton-Vassalli-College-Malta-School-of-Music-768x576.jpg 768w, https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/Main-Hall-Mikiel-Anton-Vassalli-College-Malta-School-of-Music-174x132.jpg 174w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/600;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"800\" height=\"600\" data-src=\"http:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/clearing-of-MAVC-Hall.jpg\" alt=\"\" data-id=\"975\" data-link=\"http:\/\/vpa.mikielantonvassallicollege.gov.mt\/?attachment_id=975\" class=\"wp-image-975 lazyload\" data-srcset=\"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/clearing-of-MAVC-Hall.jpg 800w, https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/clearing-of-MAVC-Hall-400x300.jpg 400w, https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/clearing-of-MAVC-Hall-768x576.jpg 768w, https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/05\/clearing-of-MAVC-Hall-174x132.jpg 174w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/600;\" \/><\/figure><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Wara li \u0121ew installati l-hand sanitisers fil-kuruturi kollha tal-iskola, l-Iskola tal-Arti Vi\u017cwali u Performattiva, qed tnedi &nbsp;\u201cSPREAD ART NOT GERMS\u201d&nbsp;g\u0127aliex l-Arti, il-Mu\u017cika, id-Drama u d-Dance huma parti mill-espressjoni tan-natura umana li tibqa\u2019 g\u0127addejja ji\u0121ri x\u2019ji\u0121ri!<\/p>\n","protected":false},"author":1,"featured_media":1273,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[14],"tags":[],"class_list":["post-1330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-mt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Xerrdu l-ARTI mhux il-mikrobi | Mikiel Anton Vassalli College<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"mt_MT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Xerrdu l-ARTI mhux il-mikrobi | Mikiel Anton Vassalli College\" \/>\n<meta property=\"og:description\" content=\"Wara li \u0121ew installati l-hand sanitisers fil-kuruturi kollha tal-iskola, l-Iskola tal-Arti Vi\u017cwali u Performattiva, qed tnedi &nbsp;\u201cSPREAD ART NOT GERMS\u201d&nbsp;g\u0127aliex l-Arti, il-Mu\u017cika, id-Drama u d-Dance huma parti mill-espressjoni tan-natura umana li tibqa\u2019 g\u0127addejja ji\u0121ri x\u2019ji\u0121ri!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/\" \/>\n<meta property=\"og:site_name\" content=\"Mikiel Anton Vassalli College\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-02T17:34:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-06T16:35:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/07\/HandSanitizer2-1024x949.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"741\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/#\/schema\/person\/75bbd2a47e20a189c08b940587000c83\"},\"headline\":\"Xerrdu l-ARTI mhux il-mikrobi\",\"datePublished\":\"2020-03-02T17:34:27+00:00\",\"dateModified\":\"2020-07-06T16:35:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/\"},\"wordCount\":52,\"image\":{\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/07\/HandSanitizer2-1024x949.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"mt-MT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/\",\"url\":\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/\",\"name\":\"Xerrdu l-ARTI mhux il-mikrobi | Mikiel Anton Vassalli College\",\"isPartOf\":{\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/07\/HandSanitizer2-1024x949.jpg\",\"datePublished\":\"2020-03-02T17:34:27+00:00\",\"dateModified\":\"2020-07-06T16:35:30+00:00\",\"author\":{\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/#\/schema\/person\/75bbd2a47e20a189c08b940587000c83\"},\"breadcrumb\":{\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#breadcrumb\"},\"inLanguage\":\"mt-MT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"mt-MT\",\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#primaryimage\",\"url\":\"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/07\/HandSanitizer2-1024x949.jpg\",\"contentUrl\":\"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/07\/HandSanitizer2-1024x949.jpg\",\"width\":800,\"height\":741},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mikielantonvassallicollege.gov.mt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Xerrdu l-ARTI mhux il-mikrobi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/#website\",\"url\":\"https:\/\/mikielantonvassallicollege.gov.mt\/\",\"name\":\"Mikiel Anton Vassalli College\",\"description\":\"Mikiel Anton Vassalli College\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mikielantonvassallicollege.gov.mt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"mt-MT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/#\/schema\/person\/75bbd2a47e20a189c08b940587000c83\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"mt-MT\",\"@id\":\"https:\/\/mikielantonvassallicollege.gov.mt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e4d1b9e7cac17e58f720ecdc1e3d185c993a9059f47126f2009ca4cf68b65190?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e4d1b9e7cac17e58f720ecdc1e3d185c993a9059f47126f2009ca4cf68b65190?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Xerrdu l-ARTI mhux il-mikrobi | Mikiel Anton Vassalli College","robots":{"index":"noindex","follow":"follow"},"og_locale":"mt_MT","og_type":"article","og_title":"Xerrdu l-ARTI mhux il-mikrobi | Mikiel Anton Vassalli College","og_description":"Wara li \u0121ew installati l-hand sanitisers fil-kuruturi kollha tal-iskola, l-Iskola tal-Arti Vi\u017cwali u Performattiva, qed tnedi &nbsp;\u201cSPREAD ART NOT GERMS\u201d&nbsp;g\u0127aliex l-Arti, il-Mu\u017cika, id-Drama u d-Dance huma parti mill-espressjoni tan-natura umana li tibqa\u2019 g\u0127addejja ji\u0121ri x\u2019ji\u0121ri!","og_url":"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/","og_site_name":"Mikiel Anton Vassalli College","article_published_time":"2020-03-02T17:34:27+00:00","article_modified_time":"2020-07-06T16:35:30+00:00","og_image":[{"width":800,"height":741,"url":"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/07\/HandSanitizer2-1024x949.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#article","isPartOf":{"@id":"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/"},"author":{"name":"admin","@id":"https:\/\/mikielantonvassallicollege.gov.mt\/#\/schema\/person\/75bbd2a47e20a189c08b940587000c83"},"headline":"Xerrdu l-ARTI mhux il-mikrobi","datePublished":"2020-03-02T17:34:27+00:00","dateModified":"2020-07-06T16:35:30+00:00","mainEntityOfPage":{"@id":"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/"},"wordCount":52,"image":{"@id":"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#primaryimage"},"thumbnailUrl":"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/07\/HandSanitizer2-1024x949.jpg","articleSection":["News"],"inLanguage":"mt-MT"},{"@type":"WebPage","@id":"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/","url":"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/","name":"Xerrdu l-ARTI mhux il-mikrobi | Mikiel Anton Vassalli College","isPartOf":{"@id":"https:\/\/mikielantonvassallicollege.gov.mt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#primaryimage"},"image":{"@id":"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#primaryimage"},"thumbnailUrl":"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/07\/HandSanitizer2-1024x949.jpg","datePublished":"2020-03-02T17:34:27+00:00","dateModified":"2020-07-06T16:35:30+00:00","author":{"@id":"https:\/\/mikielantonvassallicollege.gov.mt\/#\/schema\/person\/75bbd2a47e20a189c08b940587000c83"},"breadcrumb":{"@id":"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#breadcrumb"},"inLanguage":"mt-MT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/"]}]},{"@type":"ImageObject","inLanguage":"mt-MT","@id":"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#primaryimage","url":"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/07\/HandSanitizer2-1024x949.jpg","contentUrl":"https:\/\/mikielantonvassallicollege.gov.mt\/wp-content\/uploads\/2020\/07\/HandSanitizer2-1024x949.jpg","width":800,"height":741},{"@type":"BreadcrumbList","@id":"https:\/\/mikielantonvassallicollege.gov.mt\/spread-art-not-germs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mikielantonvassallicollege.gov.mt\/"},{"@type":"ListItem","position":2,"name":"Xerrdu l-ARTI mhux il-mikrobi"}]},{"@type":"WebSite","@id":"https:\/\/mikielantonvassallicollege.gov.mt\/#website","url":"https:\/\/mikielantonvassallicollege.gov.mt\/","name":"Mikiel Anton Vassalli College","description":"Mikiel Anton Vassalli College","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mikielantonvassallicollege.gov.mt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"mt-MT"},{"@type":"Person","@id":"https:\/\/mikielantonvassallicollege.gov.mt\/#\/schema\/person\/75bbd2a47e20a189c08b940587000c83","name":"admin","image":{"@type":"ImageObject","inLanguage":"mt-MT","@id":"https:\/\/mikielantonvassallicollege.gov.mt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e4d1b9e7cac17e58f720ecdc1e3d185c993a9059f47126f2009ca4cf68b65190?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e4d1b9e7cac17e58f720ecdc1e3d185c993a9059f47126f2009ca4cf68b65190?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/mikielantonvassallicollege.gov.mt\/mt\/wp-json\/wp\/v2\/posts\/1330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mikielantonvassallicollege.gov.mt\/mt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mikielantonvassallicollege.gov.mt\/mt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mikielantonvassallicollege.gov.mt\/mt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mikielantonvassallicollege.gov.mt\/mt\/wp-json\/wp\/v2\/comments?post=1330"}],"version-history":[{"count":1,"href":"https:\/\/mikielantonvassallicollege.gov.mt\/mt\/wp-json\/wp\/v2\/posts\/1330\/revisions"}],"predecessor-version":[{"id":1331,"href":"https:\/\/mikielantonvassallicollege.gov.mt\/mt\/wp-json\/wp\/v2\/posts\/1330\/revisions\/1331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mikielantonvassallicollege.gov.mt\/mt\/wp-json\/wp\/v2\/media\/1273"}],"wp:attachment":[{"href":"https:\/\/mikielantonvassallicollege.gov.mt\/mt\/wp-json\/wp\/v2\/media?parent=1330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mikielantonvassallicollege.gov.mt\/mt\/wp-json\/wp\/v2\/categories?post=1330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mikielantonvassallicollege.gov.mt\/mt\/wp-json\/wp\/v2\/tags?post=1330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}